{"id":5735,"date":"2024-10-07T07:39:50","date_gmt":"2024-10-07T07:39:50","guid":{"rendered":"https:\/\/vesp-epdm.com\/?p=5735"},"modified":"2024-10-07T08:13:45","modified_gmt":"2024-10-07T08:13:45","slug":"nieuwe-bestuurswissel-bij-vesp-bieke-de-langh-volgt-geert-jan-vogels-op-als-voorzitter","status":"publish","type":"post","link":"https:\/\/vesp-epdm.com\/fr-be\/nieuwe-bestuurswissel-bij-vesp-bieke-de-langh-volgt-geert-jan-vogels-op-als-voorzitter\/","title":{"rendered":"Nouveau changement au sein de la direction : Bieke De Langh succ\u00e8de \u00e0 Geert Jan Vogels \u00e0 la pr\u00e9sidence"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5735\" class=\"elementor elementor-5735\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc42d28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc42d28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1029e1c\" data-id=\"1029e1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bc4551 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bc4551\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4bff247\" data-id=\"4bff247\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62391c6 elementor-widget elementor-widget-text-editor\" data-id=\"62391c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les producteurs unis de syst\u00e8mes EPDM (VESP) annoncent fi\u00e8rement l'arriv\u00e9e d'un nouveau conseil d'administration. Apr\u00e8s des ann\u00e9es d\u2019efforts d\u00e9vou\u00e9s, le pr\u00e9sident Geert Jan Vogels (Mawipex) remet son marteau \u00e0 Bieke De Langh (VM Building Solutions). Ce changement de direction marque le d\u00e9but d'une nouvelle \u00e8re pour la VESP, dans laquelle la durabilit\u00e9 et le d\u00e9veoppement des comp\u00e9tences professionnelles resteront centrales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e594b3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e594b3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27bb79a\" data-id=\"27bb79a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d10156b elementor-widget elementor-widget-text-editor\" data-id=\"d10156b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>De nouveaux visages au sein du conseil d\u2019administration<\/strong><\/p><p>Outre l\u2019arriv\u00e9e de Bieke De Langh en tant que nouvelle pr\u00e9sidente, le conseil d\u2019administration accueille \u00e9galement Bart van Beek comme secr\u00e9taire et Benno Nijenhuis comme tr\u00e9sorier. Bart van Beek, qui remplissait jusqu'\u00e0 r\u00e9cemment le r\u00f4le de pr\u00e9sident du Comit\u00e9 Technique, transf\u00e8re sa fonction \u00e0 Sylvie Baelen. Benno Nijenhuis reste \u00e9galement actif en tant que pr\u00e9sident du comit\u00e9 des relations publiques.<\/p><p>La nouvelle pr\u00e9sidente, Bieke De Langh maintiendra et renforcera le cap fix\u00e9 par Geert Jan Vogels. Sous sa pr\u00e9sidence, la VESP souhaite non seulement garantir la qualit\u00e9 des syst\u00e8mes en EPDM, mais \u00e9galement continuer \u00e0 innover dans le domaine de la durabilit\u00e9 et du transfert de connaissances.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dd2728 elementor-widget elementor-widget-testimonial\" data-id=\"6dd2728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\u201cNotre objectif est d'am\u00e9liorer durablement les performances de nos syst\u00e8mes de toiture en EPDM, \u00e0 la fois gr\u00e2ce \u00e0 des syst\u00e8mes certifi\u00e9s que par des formations techniques sur le march\u00e9 de la toiture, avec une attention particuli\u00e8re aux avantages \u00e9cologiques, \u00e0 la dur\u00e9e de vie et \u00e0 la circularit\u00e9.\u201d <\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/vesp-epdm.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Bieke De Langh<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Pr\u00e9sidente<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ebbf515\" data-id=\"ebbf515\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b982544 elementor-widget elementor-widget-image\" data-id=\"b982544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/20241002_164558-768x1024.jpg\" class=\"attachment-large size-large wp-image-5694\" alt=\"\" srcset=\"https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/20241002_164558-768x1024.jpg 768w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/20241002_164558-225x300.jpg 225w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/20241002_164558-1152x1536.jpg 1152w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/20241002_164558-1536x2048.jpg 1536w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/20241002_164558-9x12.jpg 9w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/20241002_164558-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf418bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf418bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3eb0b2\" data-id=\"f3eb0b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d08fdc9 elementor-widget elementor-widget-text-editor\" data-id=\"d08fdc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Continuit\u00e9 et innovation en mati\u00e8re de durabilit\u00e9 et de formation<\/strong><\/p><p>Le d\u00e9part de Geert Jan Vogels marque la fin de la premi\u00e8re p\u00e9riode quinquennale au cours de laquelle la VESP a pr\u00e9sent\u00e9 son plan d\u2019action d\u00e9cennal et a r\u00e9alis\u00e9 des avanc\u00e9es significatives dans le domaine du progr\u00e8s technique et du partage des connaissances. Sous sa pr\u00e9sidence, l'association a non seulement jet\u00e9 des bases solides, mais s'est \u00e9galement impos\u00e9e sur le march\u00e9. Cette voie sera poursuivie par Bieke De Langh et le nouveau conseil d\u2019administration.<\/p><p>La VESP reste engag\u00e9e en faveur du d\u00e9veloppement durable. Dans l\u2019article <em>Nous \u00e9levons le toit \u00e0 un niveau sup\u00e9rieur<\/em> publi\u00e9 il y a quelques ann\u00e9es, la VESP a d\u00e9j\u00e0 soulign\u00e9 que le besoin de solutions durables dans le secteur de la construction est plus grand que jamais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ef326b9\" data-id=\"ef326b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fbe1da elementor-widget elementor-widget-text-editor\" data-id=\"5fbe1da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il en va de m\u00eame aujourd\u2019hui, cette n\u00e9cessit\u00e9 est m\u00eame encore plus importante. Gr\u00e2ce \u00e0 ses syst\u00e8mes en EPDM de haute qualit\u00e9, la VESP contribue \u00e0 prolonger la dur\u00e9e de vie des toitures, \u00e0 r\u00e9duire leur entretien, \u00e0 diminuer l'utilisation de nouvelles mati\u00e8res premi\u00e8res et \u00e0 favoriser une mise en \u0153uvre plus saine. Cette vision est \u00e9troitement li\u00e9e \u00e0 la mission de De Langh: <em>\"La durabilit\u00e9 devrait faire partie int\u00e9grante de tous les projets de construction, dans lesquels l'EPDM joue un r\u00f4le primordial.\u201d<\/em><\/p><p>Les membres de la VESP continuent \u00e9galement \u00e0 investir dans le domaine de la formation professionnelle. La formation de professionnels est essentielle pour garantir une mise en \u0153uvre correcte des syst\u00e8mes de toiture en EPDM.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0364d94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0364d94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c61f0d3\" data-id=\"c61f0d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5b0012 elementor-widget elementor-widget-text-editor\" data-id=\"b5b0012\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Une \u00e9quipe solide et exp\u00e9riment\u00e9e<\/strong><\/p><p>Le nouveau conseil d'administration de la VESP est compos\u00e9 de membres ayant des ann\u00e9es d'exp\u00e9rience et une connaissance approfondie du secteur. Bart van Beek, le nouvau secr\u00e9taire, est actif sur le march\u00e9 de l\u2019EPDM depuis 1994 et est co-propri\u00e9taire de Van Beek EPDM depuis 1999. Par son travail au sein du Comit\u00e9 Technique, il a contribu\u00e9 de mani\u00e8re significative \u00e0 la poursuite de la professionnalisation de la profession. Sylvie Baelen (VM Building Solutions et auparavant, secr\u00e9taire) reprend cette fonction.<\/p><p>Benno Nijenhuis, qui assume le r\u00f4le de tr\u00e9sorier, poursuit sa fonction de pr\u00e9sident du comit\u00e9 des relations publiques. Il est \u00e9galement actif sur le march\u00e9 n\u00e9erlandais de l'EPDM depuis 2007, \u00e0 la fois en tant que directeur des ventes et depuis 2012 en tant que responsable du marketing. Ces derni\u00e8res ann\u00e9es, il a d\u00e9montr\u00e9 l'importance d'une communication et de relations publiques solides pour positionner la VESP en tant qu'association professionnelle de premier plan dans le secteur. Par sa double fonction, il assure la continuit\u00e9 de l'image de l'association \u00e0 l'ext\u00e9rieur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c32277 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c32277\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d887670\" data-id=\"d887670\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea8ef9a elementor-widget elementor-widget-text-editor\" data-id=\"ea8ef9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Un regard vers l\u2019avenir : la VESP continue \u00e0 grandir et \u00e0 se d\u00e9velopper<\/strong><\/p><p>Avec ce changement de conseil d'administration, la VESP envisage l'avenir avec confiance. Le nouveau conseil d'administration continuera \u00e0 s'engager en faveur de l'innovation, de la durabilit\u00e9 et du d\u00e9veloppement de l'expertise professionnelle dans le secteur. Gr\u00e2ce \u00e0 une \u00e9troite collaboration avec les membres et les comit\u00e9s, la VESP continue de construire un avenir solide et durable pour les syst\u00e8mes de toiture en EPDM, les applications bassins en EPDM et les solutions de fa\u00e7ade en EPDM.<\/p><p>L'association donne ainsi le coup d'envoi du plan d\u2019action d\u00e9cennal pour les cinq prochaines ann\u00e9es !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b552163\" data-id=\"b552163\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3993ea elementor-widget elementor-widget-image\" data-id=\"a3993ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"377\" src=\"https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/VESP_Logo_Slogan_RGB-1024x377.jpg\" class=\"attachment-large size-large wp-image-5771\" alt=\"\" srcset=\"https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/VESP_Logo_Slogan_RGB-1024x377.jpg 1024w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/VESP_Logo_Slogan_RGB-300x110.jpg 300w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/VESP_Logo_Slogan_RGB-768x282.jpg 768w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/VESP_Logo_Slogan_RGB-1536x565.jpg 1536w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/VESP_Logo_Slogan_RGB-2048x753.jpg 2048w, https:\/\/vesp-epdm.com\/wp-content\/uploads\/2024\/10\/VESP_Logo_Slogan_RGB-18x7.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>De Verenigde EPDM Systems Producenten (VESP) kondigt met trots de komst aan van een nieuw bestuur. Na jaren van toegewijde inzet draagt Geert Jan Vogels (Mawipex) de voorzittershamer over aan Bieke De Langh (VM Building Solutions). Met deze bestuurswissel breekt er een nieuw tijdperk aan voor VESP, waarin duurzaamheid en het verhogen van vakbekwaamheid centraal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[15,17,13],"tags":[],"class_list":["post-5735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artikel","category-bestuur","category-nieuws"],"_links":{"self":[{"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/posts\/5735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/comments?post=5735"}],"version-history":[{"count":38,"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/posts\/5735\/revisions"}],"predecessor-version":[{"id":5806,"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/posts\/5735\/revisions\/5806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/media\/5775"}],"wp:attachment":[{"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/media?parent=5735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/categories?post=5735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vesp-epdm.com\/fr-be\/wp-json\/wp\/v2\/tags?post=5735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}